{"id":2485,"date":"2026-09-01T10:48:03","date_gmt":"2026-09-01T10:48:03","guid":{"rendered":"https:\/\/awaca.ipsl.fr\/?p=2485"},"modified":"2026-09-01T11:08:49","modified_gmt":"2026-09-01T11:08:49","slug":"actualite-5","status":"publish","type":"post","link":"https:\/\/awaca.ipsl.fr\/fr\/2026\/09\/01\/actualite-5\/","title":{"rendered":"12th SCAR Open Science Conference 2026 &#8211; Oslo, Norv\u00e8ge"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2485\" class=\"elementor elementor-2485\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3517e31 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3517e31\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ffc4f0\" data-id=\"5ffc4f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dc8a27f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dc8a27f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7076a6c\" data-id=\"7076a6c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97dfac2 elementor-widget elementor-widget-elementskit-heading\" data-id=\"97dfac2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><a href=\"https:\/\/scar2026.org\/\"><h1 class=\"ekit-heading--title elementskit-section-title \">12th SCAR Open Science Conference 2026 - Oslo, Norv\u00e8ge<\/h1><\/a><div class=\"ekit_heading_separetor_wraper ekit_heading_elementskit-border-divider ekit-dotted\"><div class=\"elementskit-border-divider ekit-dotted\"><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06a8c75 elementor-widget elementor-widget-text-editor\" data-id=\"06a8c75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cet \u00e9t\u00e9, une partie de l&rsquo;\u00e9quipe du projet AWACA s&rsquo;est rendue \u00e0 Oslo, en Norv\u00e8ge, pour participer \u00e0 la <strong><a href=\"https:\/\/scar2026.org\/\" data-wplink-edit=\"true\">12\u00e8me conf\u00e9rence \u00ab\u00a0Open Science\u00a0\u00bb du SCAR<\/a><\/strong> (Scientific Committee on Antarctic Research). Ce fut une excellente occasion de partager nos derniers r\u00e9sultats, d&rsquo;\u00e9changer avec la communaut\u00e9 polaire internationale et de montrer la diversit\u00e9 de nos recherches, de la logistique en milieu extr\u00eame \u00e0 la mod\u00e9lisation climatique.<\/p><p>F\u00e9licitations \u00e0 toutes nos chercheuses et tous nos chercheurs, ainsi qu\u2019\u00e0 nos ing\u00e9nieures et ing\u00e9nieurs, pour avoir fait de cette conf\u00e9rence SCAR 2026 un grand succ\u00e8s pour le projet AWACA ! Retrouvez ci-dessous l\u2019ensemble de leurs contributions.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20a12e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20a12e4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-62234df\" data-id=\"62234df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf61a7a elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"bf61a7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Pr\u00e9sentations orales : \u00e9volution des nuages et isotopes<\/strong><\/p><ul><li><p data-path-to-node=\"20,0,0\"><strong>Justine Charrel<\/strong> a inaugur\u00e9 la session S3 (\u00ab\u00a0Polar Meteorology and Atmospheric Processes\u00a0\u00bb) avec une pr\u00e9sentation <i data-path-to-node=\"7,1,0,0\" data-index-in-node=\"127\">keynote<\/i> d\u00e9di\u00e9e au transport d&rsquo;humidit\u00e9 et \u00e0 l&rsquo;\u00e9volution des nuages le long d&rsquo;un transect antarctique de 1100 km.\u00a0<\/p><\/li><li><p data-path-to-node=\"20,1,0\"><b data-path-to-node=\"20,1,0\" data-index-in-node=\"0\">Sibin Simon<\/b> a pr\u00e9sent\u00e9 ses travaux sur l&rsquo;impact des processus d&rsquo;\u00e9change air-neige sur les isotopes de l&rsquo;eau de la neige en surface, en utilisant le mod\u00e8le atmosph\u00e9rique global ICOLMDZiso.\u00a0<\/p><\/li><li><p data-path-to-node=\"20,1,0\"><b data-path-to-node=\"20,2,0\" data-index-in-node=\"0\">Feba Francis<\/b> a, de son c\u00f4t\u00e9, d\u00e9taill\u00e9 ses recherches sur l&#8217;empreinte de la glace de mer sur les isotopes de l&rsquo;eau en Antarctique.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fc8f6a3\" data-id=\"fc8f6a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aaf2b78 elementor-widget__width-initial elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"aaf2b78\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"aaf2b78\" data-elementor-lightbox-title=\"SCAWACA_1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjUwMywidXJsIjoiaHR0cHM6XC9cL2F3YWNhLmlwc2wuZnJcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA5XC9TQ0FXQUNBXzEuanBnIiwic2xpZGVzaG93IjoiYWFmMmI3OCJ9\" href=\"https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_1-800x450.jpg\" alt=\"Justine Charrel\" \/><figcaption class=\"elementor-image-carousel-caption\">Justine Charrel<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"aaf2b78\" data-elementor-lightbox-title=\"SCAWACA_2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjUwNCwidXJsIjoiaHR0cHM6XC9cL2F3YWNhLmlwc2wuZnJcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA5XC9TQ0FXQUNBXzItc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6ImFhZjJiNzgifQ%3D%3D\" href=\"https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_2-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_2-800x450.jpg\" alt=\"Sibin Simon\" \/><figcaption class=\"elementor-image-carousel-caption\">Sibin Simon<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"aaf2b78\" data-elementor-lightbox-title=\"SCAWACA_3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjUwNSwidXJsIjoiaHR0cHM6XC9cL2F3YWNhLmlwc2wuZnJcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA5XC9TQ0FXQUNBXzMtc2NhbGVkLWUxNzg4MjU3NDg4MzIzLmpwZyIsInNsaWRlc2hvdyI6ImFhZjJiNzgifQ%3D%3D\" href=\"https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_3-scaled-e1788257488323.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_3-scaled-e1788257488323-800x450.jpg\" alt=\"Francis Feba\" \/><figcaption class=\"elementor-image-carousel-caption\">Francis Feba<\/figcaption><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f86a1c9 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f86a1c9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1d9315b\" data-id=\"1d9315b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2dae87a elementor-widget__width-initial elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"2dae87a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 4\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2dae87a\" data-elementor-lightbox-title=\"SCAWACA_4\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjUwNiwidXJsIjoiaHR0cHM6XC9cL2F3YWNhLmlwc2wuZnJcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA5XC9TQ0FXQUNBXzQtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjJkYWU4N2EifQ%3D%3D\" href=\"https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_4-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_4-scaled.jpg\" alt=\"Pierre Grzegorczyk\" \/><figcaption class=\"elementor-image-carousel-caption\">Pierre Grzegorczyk<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 4\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2dae87a\" data-elementor-lightbox-title=\"SCAWACA_5\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjUwNywidXJsIjoiaHR0cHM6XC9cL2F3YWNhLmlwc2wuZnJcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA5XC9TQ0FXQUNBXzUtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjJkYWU4N2EifQ%3D%3D\" href=\"https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_5-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_5-scaled.jpg\" alt=\"Niels Dutrievoz\" \/><figcaption class=\"elementor-image-carousel-caption\">Niels Dutrievoz<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 4\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2dae87a\" data-elementor-lightbox-title=\"SCAWACA_6\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjUwOCwidXJsIjoiaHR0cHM6XC9cL2F3YWNhLmlwc2wuZnJcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA5XC9TQ0FXQUNBXzYtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjJkYWU4N2EifQ%3D%3D\" href=\"https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_6-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_6-scaled.jpg\" alt=\"\u00c9lise Fourr\u00e9\" \/><figcaption class=\"elementor-image-carousel-caption\">\u00c9lise Fourr\u00e9<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 4\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2dae87a\" data-elementor-lightbox-title=\"SCAWACA_7\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjUwOSwidXJsIjoiaHR0cHM6XC9cL2F3YWNhLmlwc2wuZnJcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA5XC9TQ0FXQUNBXzctc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjJkYWU4N2EifQ%3D%3D\" href=\"https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_7-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_7-scaled.jpg\" alt=\"In\u00e8s Ollivier\" \/><figcaption class=\"elementor-image-carousel-caption\">In\u00e8s Ollivier<\/figcaption><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8ac8574\" data-id=\"8ac8574\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c1f5bd elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8c1f5bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-path-to-node=\"2,2,0,0\"><b data-path-to-node=\"2,0\" data-index-in-node=\"0\">Sessions posters : plong\u00e9e au c\u0153ur du cycle de l&rsquo;eau<\/b><\/p><ul data-path-to-node=\"2,2\"><li><p data-path-to-node=\"2,2,0,0\"><b data-path-to-node=\"2,2,0,0\" data-index-in-node=\"0\">Pierre Grzegorczyk<\/b> a propos\u00e9 une \u00e9valuation approfondie des chutes de neige simul\u00e9es par le mod\u00e8le atmosph\u00e9rique LMDZ, en s&rsquo;appuyant sur des observations radar multi-fr\u00e9quences de la c\u00f4te jusqu&rsquo;au plateau.<\/p><\/li><li><p data-path-to-node=\"2,2,1,0\"><b data-path-to-node=\"2,2,1,0\" data-index-in-node=\"0\">Niels Dutrievoz<\/b> s&rsquo;est concentr\u00e9 sur la mod\u00e9lisation, en pr\u00e9sentant les am\u00e9liorations apport\u00e9es aux flux de surface isotopiques sur la neige dans LMDZ6iso, \u00e9valu\u00e9es sp\u00e9cifiquement au D\u00f4me C.<\/p><\/li><li><p data-path-to-node=\"2,2,2,0\"><b data-path-to-node=\"2,2,2,0\" data-index-in-node=\"0\">Ines Ollivier<\/b> a illustr\u00e9 le suivi des masses d&rsquo;air le long du transect de 1100 km, en exploitant des mesures in situ des isotopes de l&rsquo;eau, \u00e0 la fois dans la vapeur et dans les flocons de neige.<\/p><\/li><li><p data-path-to-node=\"2,2,3,0\"><b data-path-to-node=\"2,2,3,0\" data-index-in-node=\"0\">\u00c9lise Fourr\u00e9<\/b> a mis en avant les d\u00e9veloppements instrumentaux du projet, en exposant les travaux sur la mesure autonome et combin\u00e9e des isotopes de l&rsquo;eau (flocons et vapeur) \u00e0 la station Dumont d\u2019Urville.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-743fdef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"743fdef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b4ddcd0\" data-id=\"b4ddcd0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90a2428 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"90a2428\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-path-to-node=\"23\"><b data-path-to-node=\"23\" data-index-in-node=\"0\">Le d\u00e9fi logistique d&rsquo;AWACA : Vers une d\u00e9carbonation polaire<\/b><\/p><p data-path-to-node=\"23\">Au-del\u00e0 de la science atmosph\u00e9rique, le projet AWACA est un immense d\u00e9fi technologique. Nous avons contribu\u00e9 \u00e0 la session interdisciplinaire (S48) sur la d\u00e9carbonation polaire avec un poster d\u00e9di\u00e9. D\u00e9ployer trois plateformes d&rsquo;observation autonomes sur le transect de 1100 km entre Dumont D&rsquo;Urville et Concordia implique de maintenir 15 tonnes de mat\u00e9riel par site. Le vrai d\u00e9fi ? Maintenir les modules de 15 m\u00b2 \u00e0 +10\u00b0C toute l&rsquo;ann\u00e9e, alors que les temp\u00e9ratures ext\u00e9rieures chutent jusqu&rsquo;\u00e0 -60\u00b0C, avec un ensoleillement et des vents impr\u00e9visibles. Le poster d\u00e9taillait notre strat\u00e9gie \u00e9nerg\u00e9tique multi-sources (panneaux solaires, \u00e9oliennes, piles \u00e0 combustible) et les d\u00e9fis techniques impr\u00e9vus li\u00e9s \u00e0 la gestion d&rsquo;infrastructures isol\u00e9es dans l&rsquo;environnement antarctique.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d98c206 elementor-align-right elementor-mobile-align-right elementor-widget__width-initial elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"d98c206\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cliquez sur le poster pour l'agrandir<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f27efc elementor-align-right elementor-mobile-align-center elementor-widget__width-initial elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"5f27efc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-down\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cliquez sur le poster pour l'agrandir<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-81167eb\" data-id=\"81167eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee31117 elementor-widget elementor-widget-image\" data-id=\"ee31117\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/EN-V5-Poster-SCAR-Web_compressed.pdf\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_8-724x1024.jpg\" class=\"attachment-large size-large wp-image-2514\" alt=\"\" srcset=\"https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_8-724x1024.jpg 724w, https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_8-212x300.jpg 212w, https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_8-768x1086.jpg 768w, https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_8-1086x1536.jpg 1086w, https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_8-1449x2048.jpg 1449w, https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_8-8x12.jpg 8w, https:\/\/awaca.ipsl.fr\/wp-content\/uploads\/2026\/09\/SCAWACA_8-scaled.jpg 1811w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>12th SCAR Open Science Conference 2026 &#8211; Oslo, Norv\u00e8ge Cet \u00e9t\u00e9, une partie de l&rsquo;\u00e9quipe du projet AWACA s&rsquo;est rendue \u00e0 Oslo, en Norv\u00e8ge, pour participer \u00e0 la 12\u00e8me conf\u00e9rence \u00ab\u00a0Open Science\u00a0\u00bb du SCAR (Scientific Committee on Antarctic Research). Ce fut une excellente occasion de partager nos derniers r\u00e9sultats, d&rsquo;\u00e9changer avec la communaut\u00e9 polaire internationale [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"class_list":["post-2485","post","type-post","status-publish","format-standard","hentry","category-actualites","entry"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Justine Charrel","author_link":"https:\/\/awaca.ipsl.fr\/fr\/author\/jcharrel\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/awaca.ipsl.fr\/fr\/category\/actualites\/\" rel=\"category tag\">Actualit\u00e9s<\/a>","rttpg_excerpt":"12th SCAR Open Science Conference 2026 &#8211; Oslo, Norv\u00e8ge Cet \u00e9t\u00e9, une partie de l&rsquo;\u00e9quipe du projet AWACA s&rsquo;est rendue \u00e0 Oslo, en Norv\u00e8ge, pour participer \u00e0 la 12\u00e8me conf\u00e9rence \u00ab\u00a0Open Science\u00a0\u00bb du SCAR (Scientific Committee on Antarctic Research). Ce fut une excellente occasion de partager nos derniers r\u00e9sultats, d&rsquo;\u00e9changer avec la communaut\u00e9 polaire internationale\u2026","_links":{"self":[{"href":"https:\/\/awaca.ipsl.fr\/fr\/wp-json\/wp\/v2\/posts\/2485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/awaca.ipsl.fr\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/awaca.ipsl.fr\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/awaca.ipsl.fr\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/awaca.ipsl.fr\/fr\/wp-json\/wp\/v2\/comments?post=2485"}],"version-history":[{"count":20,"href":"https:\/\/awaca.ipsl.fr\/fr\/wp-json\/wp\/v2\/posts\/2485\/revisions"}],"predecessor-version":[{"id":2530,"href":"https:\/\/awaca.ipsl.fr\/fr\/wp-json\/wp\/v2\/posts\/2485\/revisions\/2530"}],"wp:attachment":[{"href":"https:\/\/awaca.ipsl.fr\/fr\/wp-json\/wp\/v2\/media?parent=2485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/awaca.ipsl.fr\/fr\/wp-json\/wp\/v2\/categories?post=2485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/awaca.ipsl.fr\/fr\/wp-json\/wp\/v2\/tags?post=2485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}